{"id":8675,"date":"2025-09-22T11:40:05","date_gmt":"2025-09-22T09:40:05","guid":{"rendered":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/"},"modified":"2025-09-22T11:40:05","modified_gmt":"2025-09-22T09:40:05","slug":"de-luxe-cake-recipe","status":"publish","type":"recipes","link":"https:\/\/www.lesaffre.pl\/en\/recipes\/de-luxe-cake-recipe\/","title":{"rendered":"De Luxe Cake &#8211; recipe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7082,"template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false},"recipe_category":[],"recipe_tag":[],"class_list":["post-8675","recipes","type-recipes","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De Luxe Cake - recipe - Lesaffre Poland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Luxe Cake - recipe - Lesaffre Poland\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/\" \/>\n<meta property=\"og:site_name\" content=\"Lesaffre Poland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/\",\"url\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/\",\"name\":\"De Luxe Cake - recipe - Lesaffre Poland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesaffre.pl\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2025\\\/09\\\/ciasto-de-lux.png\",\"datePublished\":\"2025-09-22T09:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lesaffre.pl\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2025\\\/09\\\/ciasto-de-lux.png\",\"contentUrl\":\"https:\\\/\\\/www.lesaffre.pl\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2025\\\/09\\\/ciasto-de-lux.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/de-luxe-cake-recipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lesaffre.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recipes\",\"item\":\"https:\\\/\\\/www.lesaffre.pl\\\/recipes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"De Luxe Cake &#8211; recipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#website\",\"url\":\"https:\\\/\\\/www.lesaffre.pl\\\/\",\"name\":\"Lesaffre Poland\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesaffre.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#organization\",\"name\":\"Lesaffre Poland\",\"url\":\"https:\\\/\\\/www.lesaffre.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesaffre.pl\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2022\\\/03\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.lesaffre.pl\\\/wp-content\\\/uploads\\\/sites\\\/29\\\/2022\\\/03\\\/logo.svg\",\"width\":97,\"height\":98,\"caption\":\"Lesaffre Poland\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesaffre.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Luxe Cake - recipe - Lesaffre Poland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/","og_locale":"en_US","og_type":"article","og_title":"De Luxe Cake - recipe - Lesaffre Poland","og_url":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/","og_site_name":"Lesaffre Poland","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/","url":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/","name":"De Luxe Cake - recipe - Lesaffre Poland","isPartOf":{"@id":"https:\/\/www.lesaffre.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/#primaryimage"},"image":{"@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesaffre.pl\/wp-content\/uploads\/sites\/29\/2025\/09\/ciasto-de-lux.png","datePublished":"2025-09-22T09:40:05+00:00","breadcrumb":{"@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/#primaryimage","url":"https:\/\/www.lesaffre.pl\/wp-content\/uploads\/sites\/29\/2025\/09\/ciasto-de-lux.png","contentUrl":"https:\/\/www.lesaffre.pl\/wp-content\/uploads\/sites\/29\/2025\/09\/ciasto-de-lux.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesaffre.pl\/recipes\/de-luxe-cake-recipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lesaffre.pl\/"},{"@type":"ListItem","position":2,"name":"Recipes","item":"https:\/\/www.lesaffre.pl\/recipes\/"},{"@type":"ListItem","position":3,"name":"De Luxe Cake &#8211; recipe"}]},{"@type":"WebSite","@id":"https:\/\/www.lesaffre.pl\/#website","url":"https:\/\/www.lesaffre.pl\/","name":"Lesaffre Poland","description":"","publisher":{"@id":"https:\/\/www.lesaffre.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesaffre.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lesaffre.pl\/#organization","name":"Lesaffre Poland","url":"https:\/\/www.lesaffre.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesaffre.pl\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesaffre.pl\/wp-content\/uploads\/sites\/29\/2022\/03\/logo.svg","contentUrl":"https:\/\/www.lesaffre.pl\/wp-content\/uploads\/sites\/29\/2022\/03\/logo.svg","width":97,"height":98,"caption":"Lesaffre Poland"},"image":{"@id":"https:\/\/www.lesaffre.pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/recipes\/8675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/recipes"}],"about":[{"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/types\/recipes"}],"version-history":[{"count":0,"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/recipes\/8675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/media\/7082"}],"wp:attachment":[{"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/media?parent=8675"}],"wp:term":[{"taxonomy":"recipe_category","embeddable":true,"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/recipe_category?post=8675"},{"taxonomy":"recipe_tag","embeddable":true,"href":"https:\/\/www.lesaffre.pl\/en\/wp-json\/wp\/v2\/recipe_tag?post=8675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}